{"id":1,"count":72,"description":"","link":"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/category\/uncategorized\/","name":"Uncategorized","slug":"uncategorized","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<title>Uncategorized Archives - Microsoft Translator Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/category\/uncategorized\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uncategorized Archives - Microsoft Translator Blog\" \/>\n<meta property=\"og:url\" content=\"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/category\/uncategorized\/\" \/>\n<meta property=\"og:site_name\" content=\"Microsoft Translator Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@mstranslator\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/category\/uncategorized\/\",\"url\":\"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/category\/uncategorized\/\",\"name\":\"Uncategorized Archives - Microsoft Translator Blog\",\"isPartOf\":{\"@id\":\"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/category\/uncategorized\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/category\/uncategorized\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uncategorized\"}]},{\"@type\":\"WebSite\",\"@id\":\"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/#website\",\"url\":\"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/\",\"name\":\"Microsoft Translator Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/#organization\",\"name\":\"Microsoft Corporation\",\"url\":\"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/#\/schema\/logo\/image\/\",\"url\":\"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/wp-content\/uploads\/sites\/13\/2021\/05\/microsoft_logo_element-300x300-1.png\",\"contentUrl\":\"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/wp-content\/uploads\/sites\/13\/2021\/05\/microsoft_logo_element-300x300-1.png\",\"width\":300,\"height\":300,\"caption\":\"Microsoft Corporation\"},\"image\":{\"@id\":\"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.youtube.com\/playlist?list=PLD7HFcN7LXRd4kd2XgZjIbQ8TwTC32Zc9\",\"https:\/\/www.facebook.com\/microsofttranslator\",\"https:\/\/twitter.com\/mstranslator\"]}]}<\/script>","yoast_head_json":{"title":"Uncategorized Archives - Microsoft Translator Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/category\/uncategorized\/","og_locale":"en_US","og_type":"article","og_title":"Uncategorized Archives - Microsoft Translator Blog","og_url":"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/category\/uncategorized\/","og_site_name":"Microsoft Translator Blog","twitter_card":"summary_large_image","twitter_site":"@mstranslator","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/category\/uncategorized\/","url":"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/category\/uncategorized\/","name":"Uncategorized Archives - Microsoft Translator Blog","isPartOf":{"@id":"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/#website"},"breadcrumb":{"@id":"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/category\/uncategorized\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/category\/uncategorized\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/"},{"@type":"ListItem","position":2,"name":"Uncategorized"}]},{"@type":"WebSite","@id":"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/#website","url":"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/","name":"Microsoft Translator Blog","description":"","publisher":{"@id":"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/#organization","name":"Microsoft Corporation","url":"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/#\/schema\/logo\/image\/","url":"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/wp-content\/uploads\/sites\/13\/2021\/05\/microsoft_logo_element-300x300-1.png","contentUrl":"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/wp-content\/uploads\/sites\/13\/2021\/05\/microsoft_logo_element-300x300-1.png","width":300,"height":300,"caption":"Microsoft Corporation"},"image":{"@id":"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/playlist?list=PLD7HFcN7LXRd4kd2XgZjIbQ8TwTC32Zc9","https:\/\/www.facebook.com\/microsofttranslator","https:\/\/twitter.com\/mstranslator"]}]}},"_links":{"self":[{"href":"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https://new-cm-edgedigital.pages.dev\/en-us\/translator/blog\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}