{"id":192433,"date":"1999-10-28T00:00:00","date_gmt":"1999-10-28T07:00:00","guid":{"rendered":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/msr-research-item\/a-crash-course-on-model-checking-session-1\/"},"modified":"2016-08-25T10:58:51","modified_gmt":"2016-08-25T17:58:51","slug":"a-crash-course-on-model-checking-session-1","status":"publish","type":"msr-video","link":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/video\/a-crash-course-on-model-checking-session-1\/","title":{"rendered":"A Crash Course on Model Checking &#8211; session 1"},"content":{"rendered":"<div class=\"asset-content\">\n<p>Title: A Crash Course on Model Checking<br \/>\nDate: Three Sessions: 10\/28\/99, 11\/4\/99, 11\/11\/99<br \/>\nDescription:<br \/>\nIn recent years, model checking has been widely successful in finding bugs in hardware design, and protocol design. There have been recent attempts (in the past two years) in applying model checking to improve software reliability. This course is a tutorial introduction to model checking.<\/p>\n<p>We will start with models, specification logics, and the model checking problem, which is to check if a formula holds in a model. We will survey model checking algorithms for different kinds of temporal logics. Then, we will study the state-explosion problem that arises in model construction, and various techniques to handle state-explosion (including binary decision diagrams, partial order methods, symmetry, assume-guarantee, and abstractions). We will conclude with a survey of what has been tried in applying model checking to software.<\/p>\n<p>Prerequisites: None<\/p>\n<p>Reading Materials: None<\/p>\n<\/div>\n<p><!-- .asset-content --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Title: A Crash Course on Model Checking Date: Three Sessions: 10\/28\/99, 11\/4\/99, 11\/11\/99 Description: In recent years, model checking has been widely successful in finding bugs in hardware design, and protocol design. There have been recent attempts (in the past two years) in applying model checking to improve software reliability. This course is a tutorial [&hellip;]<\/p>\n","protected":false},"featured_media":199108,"template":"","meta":{"msr-url-field":"","msr-podcast-episode":"","msrModifiedDate":"","msrModifiedDateEnabled":false,"ep_exclude_from_search":false,"_classifai_error":"","msr_hide_image_in_river":0,"footnotes":""},"research-area":[13556],"msr-video-type":[],"msr-locale":[268875],"msr-post-option":[],"msr-session-type":[],"msr-impact-theme":[],"msr-pillar":[],"msr-episode":[],"msr-research-theme":[],"class_list":["post-192433","msr-video","type-msr-video","status-publish","has-post-thumbnail","hentry","msr-research-area-artificial-intelligence","msr-locale-en_us"],"msr_download_urls":"","msr_external_url":"https:\/\/youtu.be\/qx-d8zZbeTI","msr_secondary_video_url":"","msr_video_file":"","_links":{"self":[{"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-video\/192433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-video"}],"about":[{"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/types\/msr-video"}],"version-history":[{"count":0,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-video\/192433\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/media\/199108"}],"wp:attachment":[{"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/media?parent=192433"}],"wp:term":[{"taxonomy":"msr-research-area","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/research-area?post=192433"},{"taxonomy":"msr-video-type","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-video-type?post=192433"},{"taxonomy":"msr-locale","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-locale?post=192433"},{"taxonomy":"msr-post-option","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-post-option?post=192433"},{"taxonomy":"msr-session-type","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-session-type?post=192433"},{"taxonomy":"msr-impact-theme","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-impact-theme?post=192433"},{"taxonomy":"msr-pillar","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-pillar?post=192433"},{"taxonomy":"msr-episode","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-episode?post=192433"},{"taxonomy":"msr-research-theme","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-research-theme?post=192433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}