{"id":1086570,"date":"2024-09-23T00:47:23","date_gmt":"2024-09-23T07:47:23","guid":{"rendered":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/?post_type=msr-video&#038;p=1086570"},"modified":"2024-09-23T07:49:26","modified_gmt":"2024-09-23T14:49:26","slug":"kalika-bali-the-giant-leaps-in-language-technology-and-whos-left-behind-ted-2","status":"publish","type":"msr-video","link":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/video\/kalika-bali-the-giant-leaps-in-language-technology-and-whos-left-behind-ted-2\/","title":{"rendered":"Kalika Bali, Microsoft Research @UNESCO LT4ALL"},"content":{"rendered":"<p>Kalika Bali, Principal Researcher, Microsoft Research Labs India, speaking on Evaluating Speech Data and Technology for Indian Languages<\/p>\n<p>Language Technologies for All: Enabling Linguistic Diversity and Multilingualism Worldwide<br \/>\n(Day 2 &#8211; Afternoon session)<\/p>\n<p>**Applying language technologies for linguistic diversity and multilingualism**<\/p>\n<p>Within the framework of the 2019 International Year of Indigenous Languages, a three-days International Conference will be organized. The event will contribute towards the promotion of human rights and fundamental freedoms of all language users to access information and knowledge in languages that are best understood. It also aims to encourage all relevant stakeholders to take concrete measures for the promotion of linguistic diversity, truly multilingual internet and language technologies, with special focus on indigenous languages.<\/p>\n<p>More info: <a class=\"msr-external-link glyph-append glyph-append-open-in-new-tab glyph-append-xsmall\" rel=\"noopener noreferrer\" target=\"_blank\" href=\"https:\/\/en.unesco.org\/LT4All\">https:\/\/en.unesco.org\/LT4All<span class=\"sr-only\"> (opens in new tab)<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kalika Bali, Principal Researcher, Microsoft Research Labs India, speaking on Evaluating Speech Data and Technology for Indian Languages Language Technologies for All: Enabling Linguistic Diversity and Multilingualism Worldwide (Day 2 &#8211; Afternoon session) **Applying language technologies for linguistic diversity and multilingualism** Within the framework of the 2019 International Year of Indigenous Languages, a three-days International [&hellip;]<\/p>\n","protected":false},"featured_media":1086573,"template":"","meta":{"msr-url-field":"","msr-podcast-episode":"","msrModifiedDate":"","msrModifiedDateEnabled":false,"ep_exclude_from_search":false,"_classifai_error":"","msr_hide_image_in_river":0,"footnotes":""},"research-area":[13545,13568],"msr-video-type":[],"msr-locale":[268875],"msr-post-option":[],"msr-session-type":[],"msr-impact-theme":[],"msr-pillar":[],"msr-episode":[],"msr-research-theme":[],"class_list":["post-1086570","msr-video","type-msr-video","status-publish","has-post-thumbnail","hentry","msr-research-area-human-language-technologies","msr-research-area-technology-for-emerging-markets","msr-locale-en_us"],"msr_download_urls":"","msr_external_url":"https:\/\/youtu.be\/eKezpAr_-Q0?si=sD136kMbTXWQv-th","msr_secondary_video_url":"","msr_video_file":"http:\/\/0","_links":{"self":[{"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-video\/1086570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-video"}],"about":[{"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/types\/msr-video"}],"version-history":[{"count":2,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-video\/1086570\/revisions"}],"predecessor-version":[{"id":1087125,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-video\/1086570\/revisions\/1087125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/media\/1086573"}],"wp:attachment":[{"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/media?parent=1086570"}],"wp:term":[{"taxonomy":"msr-research-area","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/research-area?post=1086570"},{"taxonomy":"msr-video-type","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-video-type?post=1086570"},{"taxonomy":"msr-locale","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-locale?post=1086570"},{"taxonomy":"msr-post-option","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-post-option?post=1086570"},{"taxonomy":"msr-session-type","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-session-type?post=1086570"},{"taxonomy":"msr-impact-theme","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-impact-theme?post=1086570"},{"taxonomy":"msr-pillar","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-pillar?post=1086570"},{"taxonomy":"msr-episode","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-episode?post=1086570"},{"taxonomy":"msr-research-theme","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-research-theme?post=1086570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}