{"id":909627,"date":"2022-12-21T01:33:26","date_gmt":"2022-12-21T09:33:26","guid":{"rendered":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/"},"modified":"2022-12-21T01:34:52","modified_gmt":"2022-12-21T09:34:52","slug":"an-integrated-neural-and-algorithmic-system-for-optical-flow-computation-2","status":"publish","type":"msr-research-item","link":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/publication\/an-integrated-neural-and-algorithmic-system-for-optical-flow-computation-2\/","title":{"rendered":"An Integrated Neural and Algorithmic System for Optical Flow Computation"},"content":{"rendered":"\n\n\n<p class=\"wp-block-paragraph\">Motion detection plays a central role in several visual environments: knowledge of object velocities and trajectories is fundamental in scene interpretation and segmentation. This task appears a simple problem, but detecting moving objects is very difficult, in fact this is a problem that cannot be considered completely solved today [1] [2] [3].<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Motion detection plays a central role in several visual environments: knowledge of object velocities and trajectories is fundamental in scene interpretation and segmentation. This task appears a simple problem, but detecting moving objects is very difficult, in fact this is a problem that cannot be considered completely solved today [1] [2] [3].<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"msr-url-field":"","msr-podcast-episode":"","msrModifiedDate":"","msrModifiedDateEnabled":false,"ep_exclude_from_search":false,"_classifai_error":"","msr-author-ordering":[{"type":"user_nicename","value":"Antonio Criminisi","user_id":"41790"},{"type":"guest","value":"g-a-m-gioiello","user_id":"909630"},{"type":"guest","value":"d-molinelli","user_id":"909633"},{"type":"guest","value":"f-sorbello","user_id":"909636"}],"msr_publishername":"Springer, London","msr_publisher_other":"","msr_booktitle":"","msr_chapter":"","msr_edition":"","msr_editors":"","msr_how_published":"","msr_isbn":"","msr_issue":"","msr_journal":"","msr_number":"","msr_organization":"","msr_pages_string":"304\u2013309","msr_page_range_start":"304","msr_page_range_end":"309","msr_series":"","msr_volume":"","msr_copyright":"","msr_conference_name":"Italian Workshop on Neural Nets","msr_doi":"10.1007\/978-1-4471-0951-8_35","msr_arxiv_id":"","msr_mag_id":"249739884","msr_other_authors":"","msr_other_contributors":"","msr_speaker":"","msr_award":"","msr_affiliation":"","msr_institution":"","msr_host":"","msr_version":"","msr_duration":"","msr_release_tracker_id":"","msr_highlight_type":"","msr_date_display_format":"","msr_main_download_label":"","msr_external_link_label":"","msr_doi_label":"","msr_published_date":"1996-05-01","msr_startdate":"","msr_presentation_date":"","msr_highlight_text":"","msr_notes":"","msr_longbiography":"","msr_publicationurl":"","msr_external_url":"","msr_secondary_video_url":"","msr_conference_url":"","msr_journal_url":"","msr_year":1996,"msr_month":5,"msr_day":1,"msr_microsoftintellectualproperty":true,"msr_pub_id":"","msr_publication_uploader":[{"type":"doi","viewUrl":"false","id":false,"title":"10.1007\/978-1-4471-0951-8_35","label_id":243106,"label":0},{"type":"url","viewUrl":"false","id":false,"title":"https:\/\/link.springer.com\/chapter\/10.1007\/978-1-4471-0951-8_35","label_id":243109,"label":0},{"type":"url","viewUrl":"false","id":false,"title":"https:\/\/rd.springer.com\/chapter\/10.1007\/978-1-4471-0951-8_35","label_id":243109,"label":0},{"type":"url","viewUrl":"false","id":false,"title":"https:\/\/research.microsoft.com\/apps\/pubs\/default.aspx?id=67259","label_id":243109,"label":0},{"type":"url","viewUrl":"false","id":false,"title":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/publication\/an-integrated-neural-and-algorithmic-system-for-optical-flow-computation\/","label_id":243109,"label":0}],"msr_related_uploader":[],"msr_original_fields_of_study":["Computer vision","Computer science","Artificial intelligence","Motion detection","Segmentation","Optical flow","Epipolar geometry","Optical flow computation","Fundamental matrix (computer vision)","Epipolar line"],"msr_s2_paper_id":"","msr_s2_pdf_url":"","msr_citation_count_updated":"","msr_citation_count":0,"msr_influential_citations":0,"msr_reference_count":0,"msr_s2_open_access":false,"msr_s2_author_ids":[],"msr_pub_ids":[],"msr_hide_image_in_river":0,"footnotes":""},"msr-research-highlight":[],"research-area":[13562],"msr-publication-type":[193716],"msr-publisher":[],"msr-publication-cta":[],"msr-focus-area":[],"msr-locale":[268875],"msr-post-option":[],"msr-field-of-study":[246694,246691,246688,254140,267213,267210,247720,254017,267207,247783],"msr-conference":[267216],"msr-journal":[],"msr-impact-theme":[],"msr-pillar":[],"class_list":["post-909627","msr-research-item","type-msr-research-item","status-publish","hentry","msr-research-area-computer-vision","msr-locale-en_us","msr-field-of-study-artificial-intelligence","msr-field-of-study-computer-science","msr-field-of-study-computer-vision","msr-field-of-study-epipolar-geometry","msr-field-of-study-epipolar-line","msr-field-of-study-fundamental-matrix-computer-vision","msr-field-of-study-motion-detection","msr-field-of-study-optical-flow","msr-field-of-study-optical-flow-computation","msr-field-of-study-segmentation"],"msr_publishername":"Springer, London","msr_edition":"","msr_affiliation":"","msr_published_date":"1996-05-01","msr_host":"","msr_duration":"","msr_version":"","msr_speaker":"","msr_other_contributors":"","msr_booktitle":"","msr_pages_string":"304\u2013309","msr_chapter":"","msr_isbn":"","msr_journal":"","msr_volume":"","msr_number":"","msr_editors":"","msr_series":"","msr_issue":"","msr_organization":"","msr_how_published":"","msr_notes":"","msr_highlight_text":"","msr_release_tracker_id":"","msr_original_fields_of_study":"","msr_download_urls":"","msr_external_url":"","msr_secondary_video_url":"","msr_longbiography":"","msr_microsoftintellectualproperty":1,"msr_main_download":"","msr_publicationurl":"","msr_doi":"10.1007\/978-1-4471-0951-8_35","msr_publication_uploader":[{"type":"doi","viewUrl":"false","id":"false","title":"10.1007\/978-1-4471-0951-8_35","label_id":"243106","label":0},{"type":"url","viewUrl":"false","id":"false","title":"https:\/\/link.springer.com\/chapter\/10.1007\/978-1-4471-0951-8_35","label_id":"243109","label":0},{"type":"url","viewUrl":"false","id":"false","title":"https:\/\/rd.springer.com\/chapter\/10.1007\/978-1-4471-0951-8_35","label_id":"243109","label":0},{"type":"url","viewUrl":"false","id":"false","title":"https:\/\/research.microsoft.com\/apps\/pubs\/default.aspx?id=67259","label_id":"243109","label":0},{"type":"url","viewUrl":"false","id":"false","title":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/publication\/an-integrated-neural-and-algorithmic-system-for-optical-flow-computation\/","label_id":"243109","label":0}],"msr_related_uploader":[],"msr_citation_count":0,"msr_citation_count_updated":"","msr_s2_paper_id":"","msr_influential_citations":0,"msr_reference_count":0,"msr_arxiv_id":"","msr_s2_author_ids":[],"msr_s2_open_access":false,"msr_s2_pdf_url":null,"msr_attachments":[],"msr-author-ordering":[{"type":"user_nicename","value":"Antonio Criminisi","user_id":41790,"rest_url":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/microsoft-research\/v1\/researchers?person=Antonio Criminisi"},{"type":"guest","value":"g-a-m-gioiello","user_id":909630,"rest_url":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/microsoft-research\/v1\/researchers?person=g-a-m-gioiello"},{"type":"guest","value":"d-molinelli","user_id":909633,"rest_url":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/microsoft-research\/v1\/researchers?person=d-molinelli"},{"type":"guest","value":"f-sorbello","user_id":909636,"rest_url":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/microsoft-research\/v1\/researchers?person=f-sorbello"}],"msr_impact_theme":[],"msr_research_lab":[],"msr_event":[],"msr_group":[],"msr_project":[],"publication":[],"video":[],"msr-tool":[],"msr_publication_type":"inproceedings","related_content":[],"_links":{"self":[{"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-research-item\/909627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-research-item"}],"about":[{"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/types\/msr-research-item"}],"version-history":[{"count":1,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-research-item\/909627\/revisions"}],"predecessor-version":[{"id":909639,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-research-item\/909627\/revisions\/909639"}],"wp:attachment":[{"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/media?parent=909627"}],"wp:term":[{"taxonomy":"msr-research-highlight","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-research-highlight?post=909627"},{"taxonomy":"msr-research-area","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/research-area?post=909627"},{"taxonomy":"msr-publication-type","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-publication-type?post=909627"},{"taxonomy":"msr-publisher","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-publisher?post=909627"},{"taxonomy":"msr-publication-cta","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-publication-cta?post=909627"},{"taxonomy":"msr-focus-area","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-focus-area?post=909627"},{"taxonomy":"msr-locale","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-locale?post=909627"},{"taxonomy":"msr-post-option","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-post-option?post=909627"},{"taxonomy":"msr-field-of-study","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-field-of-study?post=909627"},{"taxonomy":"msr-conference","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-conference?post=909627"},{"taxonomy":"msr-journal","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-journal?post=909627"},{"taxonomy":"msr-impact-theme","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-impact-theme?post=909627"},{"taxonomy":"msr-pillar","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-pillar?post=909627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}