{"id":693390,"date":"2020-09-21T12:00:48","date_gmt":"2020-09-21T19:00:48","guid":{"rendered":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/?post_type=msr-research-item&#038;p=693390"},"modified":"2023-05-26T11:29:10","modified_gmt":"2023-05-26T18:29:10","slug":"task-oriented-dialogue-as-dataflow-synthesis","status":"publish","type":"msr-research-item","link":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/publication\/task-oriented-dialogue-as-dataflow-synthesis\/","title":{"rendered":"Task-Oriented Dialogue as Dataflow Synthesis"},"content":{"rendered":"\n\n\n<p class=\"wp-block-paragraph\">We describe an approach to task-oriented dialogue in which dialogue state is represented as a dataflow graph. A dialogue agent maps each user utterance to a program that extends this graph. Programs include metacomputation operators for reference and revision that reuse dataflow fragments from previous turns. Our graph-based state enables the expression and manipulation of complex user intents, and explicit metacomputation makes these intents easier for learned models to predict. We introduce a new dataset, SMCalFlow, featuring complex dialogues about events, weather, places, and people. Experiments show that dataflow graphs and metacomputation substantially improve representability and predictability in these natural dialogues. Additional experiments on the MultiWOZ dataset show that our dataflow representation enables an otherwise off-the-shelf sequence-to-sequence model to match the best existing task-specific state tracking model. The SMCalFlow dataset, code for replicating experiments, and a public leaderboard are available at <a href=\"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/project\/dataflow-based-dialogue-semantic-machines\">https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/project\/dataflow-based-dialogue-semantic-machines<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>We describe an approach to task-oriented dialogue in which dialogue state is represented as a dataflow graph. A dialogue agent maps each user utterance to a program that extends this graph. Programs include metacomputation operators for reference and revision that reuse dataflow fragments from previous turns. Our graph-based state enables the expression and manipulation of [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"msr-url-field":"","msr-podcast-episode":"","msrModifiedDate":"","msrModifiedDateEnabled":false,"ep_exclude_from_search":false,"_classifai_error":"","msr-author-ordering":[{"type":"user_nicename","value":"Jacob Andreas","user_id":"39138"},{"type":"guest","value":"john-bufe","user_id":"765268"},{"type":"user_nicename","value":"David Burkett","user_id":"40369"},{"type":"text","value":"Charles Chen","user_id":0},{"type":"text","value":"Josh Clausman","user_id":0},{"type":"user_nicename","value":"Jean Crawford","user_id":"39486"},{"type":"text","value":"Kate Crim","user_id":0},{"type":"text","value":"Jordan DeLoach","user_id":0},{"type":"text","value":"Leah Dorner","user_id":0},{"type":"user_nicename","value":"Jason Eisner","user_id":"39970"},{"type":"user_nicename","value":"Hao Fang","user_id":"39465"},{"type":"text","value":"Alan Guo","user_id":0},{"type":"text","value":"David Hall","user_id":0},{"type":"text","value":"Kristin Hayes","user_id":0},{"type":"text","value":"Kellie Hill","user_id":0},{"type":"text","value":"Diana Ho","user_id":0},{"type":"text","value":"Wendy Iwaszuk","user_id":0},{"type":"text","value":"Smriti Jha","user_id":0},{"type":"user_nicename","value":"Dan Klein","user_id":"40909"},{"type":"user_nicename","value":"Jayant Krishnamurthy","user_id":"39519"},{"type":"text","value":"Theo Lanman","user_id":0},{"type":"user_nicename","value":"Percy Liang","user_id":"40402"},{"type":"text","value":"Christopher H. Lin","user_id":0},{"type":"text","value":"Ilya Lintsbakh","user_id":0},{"type":"text","value":"Andy McGovern","user_id":0},{"type":"text","value":"Aleksandr Nisnevich","user_id":0},{"type":"user_nicename","value":"Adam Pauls","user_id":"39483"},{"type":"text","value":"Dmitrij Petters","user_id":0},{"type":"text","value":"Brent Read","user_id":0},{"type":"text","value":"Dan Roth","user_id":0},{"type":"user_nicename","value":"Subhro Roy","user_id":"39513"},{"type":"text","value":"Jesse Rusak","user_id":0},{"type":"text","value":"Beth Short","user_id":0},{"type":"text","value":"Div Slomin","user_id":0},{"type":"user_nicename","value":"Benjamin Snyder","user_id":"40363"},{"type":"text","value":"Stephon Striplin","user_id":0},{"type":"user_nicename","value":"Yu Su","user_id":"39492"},{"type":"text","value":"Zachary Tellman","user_id":0},{"type":"user_nicename","value":"Sam Thomson","user_id":"40354"},{"type":"text","value":"Andrei Vorobev","user_id":0},{"type":"text","value":"Izabela Witoszko","user_id":0},{"type":"user_nicename","value":"Jason Wolfe","user_id":"39480"},{"type":"text","value":"Abby Wray","user_id":0},{"type":"user_nicename","value":"Yuchen Zhang","user_id":"39477"},{"type":"text","value":"Alexander Zotov","user_id":0}],"msr_publishername":"","msr_publisher_other":"","msr_booktitle":"","msr_chapter":"","msr_edition":"","msr_editors":"","msr_how_published":"","msr_isbn":"","msr_issue":"","msr_journal":"Transactions of the Association for Computational Linguistics","msr_number":"","msr_organization":"","msr_pages_string":"556\u2013571","msr_page_range_start":"556","msr_page_range_end":"571","msr_series":"","msr_volume":"8","msr_copyright":"","msr_conference_name":"","msr_doi":"10.1162\/TACL_A_00333","msr_arxiv_id":"","msr_mag_id":"3105388824","msr_other_authors":"","msr_other_contributors":"","msr_speaker":"","msr_award":"","msr_affiliation":"","msr_institution":"","msr_host":"","msr_version":"","msr_duration":"","msr_release_tracker_id":"","msr_highlight_type":"","msr_date_display_format":"","msr_main_download_label":"","msr_external_link_label":"","msr_doi_label":"","msr_published_date":"2020-09-20","msr_startdate":"","msr_presentation_date":"","msr_highlight_text":"","msr_notes":"","msr_longbiography":"","msr_publicationurl":"","msr_external_url":"","msr_secondary_video_url":"","msr_conference_url":"","msr_journal_url":"","msr_year":2020,"msr_month":9,"msr_day":20,"msr_microsoftintellectualproperty":true,"msr_pub_id":"","msr_publication_uploader":[{"type":"url","viewUrl":"false","id":false,"title":"https:\/\/www.mitpressjournals.org\/doi\/10.1162\/tacl_a_00333","label_id":243109,"label":0},{"type":"url","viewUrl":"false","id":false,"title":"https:\/\/arxiv.org\/abs\/2009.11423","label_id":252679,"label":0},{"type":"doi","viewUrl":"false","id":false,"title":"10.1162\/TACL_A_00333","label_id":243106,"label":0}],"msr_related_uploader":[],"msr_original_fields_of_study":["Computer science","Programming language","Dataflow","Graph (abstract data type)","Task oriented","Utterance"],"msr_s2_paper_id":"","msr_s2_pdf_url":"","msr_citation_count_updated":"","msr_citation_count":0,"msr_influential_citations":0,"msr_reference_count":0,"msr_s2_open_access":false,"msr_s2_author_ids":[],"msr_pub_ids":[],"msr_hide_image_in_river":0,"footnotes":""},"msr-research-highlight":[],"research-area":[13556],"msr-publication-type":[193715],"msr-publisher":[],"msr-publication-cta":[],"msr-focus-area":[],"msr-locale":[268875],"msr-post-option":[],"msr-field-of-study":[246691,249301,251620,249202,252244,252499],"msr-conference":[],"msr-journal":[],"msr-impact-theme":[],"msr-pillar":[],"class_list":["post-693390","msr-research-item","type-msr-research-item","status-publish","hentry","msr-research-area-artificial-intelligence","msr-locale-en_us","msr-field-of-study-computer-science","msr-field-of-study-dataflow","msr-field-of-study-graph-abstract-data-type","msr-field-of-study-programming-language","msr-field-of-study-task-oriented","msr-field-of-study-utterance"],"msr_publishername":"","msr_edition":"","msr_affiliation":"","msr_published_date":"2020-09-20","msr_host":"","msr_duration":"","msr_version":"","msr_speaker":"","msr_other_contributors":"","msr_booktitle":"","msr_pages_string":"556\u2013571","msr_chapter":"","msr_isbn":"","msr_journal":"Transactions of the Association for Computational Linguistics","msr_volume":"8","msr_number":"","msr_editors":"","msr_series":"","msr_issue":"","msr_organization":"","msr_how_published":"","msr_notes":"","msr_highlight_text":"","msr_release_tracker_id":"","msr_original_fields_of_study":"","msr_download_urls":"","msr_external_url":"","msr_secondary_video_url":"","msr_longbiography":"","msr_microsoftintellectualproperty":1,"msr_main_download":"","msr_publicationurl":"","msr_doi":"10.1162\/TACL_A_00333","msr_publication_uploader":[{"type":"url","viewUrl":"false","id":"false","title":"https:\/\/www.mitpressjournals.org\/doi\/10.1162\/tacl_a_00333","label_id":"243109","label":0},{"type":"url","viewUrl":"false","id":"false","title":"https:\/\/arxiv.org\/abs\/2009.11423","label_id":"252679","label":0},{"type":"doi","viewUrl":"false","id":"false","title":"10.1162\/TACL_A_00333","label_id":"243106","label":0}],"msr_related_uploader":[],"msr_citation_count":0,"msr_citation_count_updated":"","msr_s2_paper_id":"","msr_influential_citations":0,"msr_reference_count":0,"msr_arxiv_id":"","msr_s2_author_ids":[],"msr_s2_open_access":false,"msr_s2_pdf_url":null,"msr_attachments":[],"msr-author-ordering":[{"type":"user_nicename","value":"Jacob Andreas","user_id":39138,"rest_url":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/microsoft-research\/v1\/researchers?person=Jacob Andreas"},{"type":"guest","value":"john-bufe","user_id":765268,"rest_url":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/microsoft-research\/v1\/researchers?person=john-bufe"},{"type":"user_nicename","value":"David Burkett","user_id":40369,"rest_url":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/microsoft-research\/v1\/researchers?person=David Burkett"},{"type":"text","value":"Charles Chen","user_id":0,"rest_url":false},{"type":"text","value":"Josh Clausman","user_id":0,"rest_url":false},{"type":"user_nicename","value":"Jean Crawford","user_id":39486,"rest_url":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/microsoft-research\/v1\/researchers?person=Jean Crawford"},{"type":"text","value":"Kate Crim","user_id":0,"rest_url":false},{"type":"text","value":"Jordan DeLoach","user_id":0,"rest_url":false},{"type":"text","value":"Leah Dorner","user_id":0,"rest_url":false},{"type":"user_nicename","value":"Jason Eisner","user_id":39970,"rest_url":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/microsoft-research\/v1\/researchers?person=Jason Eisner"},{"type":"user_nicename","value":"Hao Fang","user_id":39465,"rest_url":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/microsoft-research\/v1\/researchers?person=Hao Fang"},{"type":"text","value":"Alan Guo","user_id":0,"rest_url":false},{"type":"text","value":"David Hall","user_id":0,"rest_url":false},{"type":"text","value":"Kristin Hayes","user_id":0,"rest_url":false},{"type":"text","value":"Kellie Hill","user_id":0,"rest_url":false},{"type":"text","value":"Diana Ho","user_id":0,"rest_url":false},{"type":"text","value":"Wendy Iwaszuk","user_id":0,"rest_url":false},{"type":"text","value":"Smriti Jha","user_id":0,"rest_url":false},{"type":"user_nicename","value":"Dan Klein","user_id":40909,"rest_url":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/microsoft-research\/v1\/researchers?person=Dan Klein"},{"type":"user_nicename","value":"Jayant Krishnamurthy","user_id":39519,"rest_url":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/microsoft-research\/v1\/researchers?person=Jayant Krishnamurthy"},{"type":"text","value":"Theo Lanman","user_id":0,"rest_url":false},{"type":"user_nicename","value":"Percy Liang","user_id":40402,"rest_url":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/microsoft-research\/v1\/researchers?person=Percy Liang"},{"type":"text","value":"Christopher H. Lin","user_id":0,"rest_url":false},{"type":"text","value":"Ilya Lintsbakh","user_id":0,"rest_url":false},{"type":"text","value":"Andy McGovern","user_id":0,"rest_url":false},{"type":"text","value":"Aleksandr Nisnevich","user_id":0,"rest_url":false},{"type":"user_nicename","value":"Adam Pauls","user_id":39483,"rest_url":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/microsoft-research\/v1\/researchers?person=Adam Pauls"},{"type":"text","value":"Dmitrij Petters","user_id":0,"rest_url":false},{"type":"text","value":"Brent Read","user_id":0,"rest_url":false},{"type":"text","value":"Dan Roth","user_id":0,"rest_url":false},{"type":"user_nicename","value":"Subhro Roy","user_id":39513,"rest_url":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/microsoft-research\/v1\/researchers?person=Subhro Roy"},{"type":"text","value":"Jesse Rusak","user_id":0,"rest_url":false},{"type":"text","value":"Beth Short","user_id":0,"rest_url":false},{"type":"text","value":"Div Slomin","user_id":0,"rest_url":false},{"type":"user_nicename","value":"Benjamin Snyder","user_id":40363,"rest_url":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/microsoft-research\/v1\/researchers?person=Benjamin Snyder"},{"type":"text","value":"Stephon Striplin","user_id":0,"rest_url":false},{"type":"user_nicename","value":"Yu Su","user_id":39492,"rest_url":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/microsoft-research\/v1\/researchers?person=Yu Su"},{"type":"text","value":"Zachary Tellman","user_id":0,"rest_url":false},{"type":"user_nicename","value":"Sam Thomson","user_id":40354,"rest_url":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/microsoft-research\/v1\/researchers?person=Sam Thomson"},{"type":"text","value":"Andrei Vorobev","user_id":0,"rest_url":false},{"type":"text","value":"Izabela Witoszko","user_id":0,"rest_url":false},{"type":"user_nicename","value":"Jason Wolfe","user_id":39480,"rest_url":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/microsoft-research\/v1\/researchers?person=Jason Wolfe"},{"type":"text","value":"Abby Wray","user_id":0,"rest_url":false},{"type":"user_nicename","value":"Yuchen Zhang","user_id":39477,"rest_url":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/microsoft-research\/v1\/researchers?person=Yuchen Zhang"},{"type":"text","value":"Alexander Zotov","user_id":0,"rest_url":false}],"msr_impact_theme":[],"msr_research_lab":[],"msr_event":[],"msr_group":[],"msr_project":[],"publication":[],"video":[],"msr-tool":[696625],"msr_publication_type":"article","related_content":[],"_links":{"self":[{"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-research-item\/693390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-research-item"}],"about":[{"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/types\/msr-research-item"}],"version-history":[{"count":8,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-research-item\/693390\/revisions"}],"predecessor-version":[{"id":751870,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-research-item\/693390\/revisions\/751870"}],"wp:attachment":[{"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/media?parent=693390"}],"wp:term":[{"taxonomy":"msr-research-highlight","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-research-highlight?post=693390"},{"taxonomy":"msr-research-area","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/research-area?post=693390"},{"taxonomy":"msr-publication-type","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-publication-type?post=693390"},{"taxonomy":"msr-publisher","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-publisher?post=693390"},{"taxonomy":"msr-publication-cta","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-publication-cta?post=693390"},{"taxonomy":"msr-focus-area","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-focus-area?post=693390"},{"taxonomy":"msr-locale","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-locale?post=693390"},{"taxonomy":"msr-post-option","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-post-option?post=693390"},{"taxonomy":"msr-field-of-study","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-field-of-study?post=693390"},{"taxonomy":"msr-conference","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-conference?post=693390"},{"taxonomy":"msr-journal","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-journal?post=693390"},{"taxonomy":"msr-impact-theme","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-impact-theme?post=693390"},{"taxonomy":"msr-pillar","embeddable":true,"href":"https:\/\/new-cm-edgedigital.pages.dev\/en-us\/research\/wp-json\/wp\/v2\/msr-pillar?post=693390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}